{"id":3076,"date":"2025-09-01T11:00:49","date_gmt":"2025-09-01T11:00:49","guid":{"rendered":"https:\/\/www.apostolicosanjose.edu.py\/web\/?p=3076"},"modified":"2025-10-21T13:06:20","modified_gmt":"2025-10-21T13:06:20","slug":"programa-nivel-inicial-pre-escolar","status":"publish","type":"post","link":"https:\/\/www.apostolicosanjose.edu.py\/web\/programa-nivel-inicial-pre-escolar\/","title":{"rendered":"PROGRAMA NIVEL INICIAL PRE-ESCOLAR"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><u>PRE-ESCOLAR<\/u><\/strong><\/p>\n<p style=\"text-align: left;\">Ofrece horario extendido (primera y segunda jornada) con espacios pedag\u00f3gico\/acad\u00e9micos, l\u00fadico\/recreativo, almuerzo y momentos de descanso.<\/p>\n<p style=\"text-align: left;\"><strong>Primera jornada de 7:00 a 11:30hs.<\/strong><\/p>\n<p style=\"text-align: left;\">Clases pedag\u00f3gica\/acad\u00e9mica con las profesoras de grado para cumplir con el plan de estudio del MEC.<\/p>\n<p style=\"text-align: left;\">Ingl\u00e9s con profesores y programa de estudio del CCPA, religi\u00f3n.<\/p>\n<p style=\"text-align: left;\">De 11:30 a 12:10hs<\/p>\n<p style=\"text-align: left;\">Almuerzo en comedores destinados y equipados para cada secci\u00f3n.<\/p>\n<p style=\"text-align: left;\">De 12:20 a 13:00hs<\/p>\n<p style=\"text-align: left;\">Momento de descanso en salas equipadas con colchonetas para cada secci\u00f3n.<\/p>\n<p style=\"text-align: left;\"><strong>Segunda jornada de 13:00 a 15:10hs.<\/strong><\/p>\n<p style=\"text-align: left;\">Espacios l\u00fadico\/pedag\u00f3gico de<\/p>\n<ul>\n<li><strong>Deporte.<\/strong><\/li>\n<li><strong>Danza.<\/strong><\/li>\n<li><strong>Inform\u00e1tica.<\/strong><\/li>\n<li><strong>Psicomotricidad.<\/strong><\/li>\n<li><strong>M\u00fasica<\/strong><\/li>\n<\/ul>\n<p><strong>*Con Profesores capacitados en estas \u00e1reas\u00a0<\/strong><\/p>\n<ul>\n<li><strong>Expresi\u00f3n literaria.<\/strong><\/li>\n<li><strong>Expresi\u00f3n art\u00edstica<\/strong><\/li>\n<\/ul>\n<p><strong>*Con profesores de grado.<\/strong><\/p>\n<p style=\"text-align: center;\">Cuenta con dos profesoras de grado: una titular y una auxiliar, recibidas en Licenciatura de Educaci\u00f3n Inicial, Licenciatura de Psicopedagog\u00eda, Licenciatura en Fonoaudiolog\u00eda o Terapia Ocupacional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3605 aligncenter\" src=\"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-content\/uploads\/2023\/08\/preescolar-723x1024.jpg\" alt=\"\" width=\"309\" height=\"438\" srcset=\"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-content\/uploads\/2023\/08\/preescolar-723x1024.jpg 723w, https:\/\/www.apostolicosanjose.edu.py\/web\/wp-content\/uploads\/2023\/08\/preescolar-212x300.jpg 212w, https:\/\/www.apostolicosanjose.edu.py\/web\/wp-content\/uploads\/2023\/08\/preescolar-768x1087.jpg 768w, https:\/\/www.apostolicosanjose.edu.py\/web\/wp-content\/uploads\/2023\/08\/preescolar.jpg 904w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRE-ESCOLAR Ofrece horario extendido (primera y segunda jornada) con espacios pedag\u00f3gico\/acad\u00e9micos, l\u00fadico\/recreativo, almuerzo y momentos de descanso. Primera jornada de 7:00 a 11:30hs. Clases pedag\u00f3gica\/acad\u00e9mica con las profesoras de grado para cumplir con el plan de estudio del MEC. Ingl\u00e9s con profesores y programa de estudio del CCPA, religi\u00f3n. De 11:30 a 12:10hs Almuerzo en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[538],"tags":[],"class_list":["post-3076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-horario-de-clases"],"_links":{"self":[{"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/posts\/3076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/comments?post=3076"}],"version-history":[{"count":7,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/posts\/3076\/revisions"}],"predecessor-version":[{"id":3606,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/posts\/3076\/revisions\/3606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/media\/3605"}],"wp:attachment":[{"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/media?parent=3076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/categories?post=3076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apostolicosanjose.edu.py\/web\/wp-json\/wp\/v2\/tags?post=3076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}